{"id":3614,"date":"2026-03-20T00:51:32","date_gmt":"2026-03-20T03:51:32","guid":{"rendered":"https:\/\/victorhutt.com.ar\/?p=3614"},"modified":"2026-04-13T22:09:31","modified_gmt":"2026-04-14T01:09:31","slug":"un-analisis-del-proyecto-de-reforma-previsional","status":"publish","type":"post","link":"https:\/\/victorhutt.com.ar\/index.php\/2026\/03\/20\/un-analisis-del-proyecto-de-reforma-previsional\/","title":{"rendered":"Un an\u00e1lisis del proyecto de reforma previsional"},"content":{"rendered":"\r\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>An\u00e1lisis del proyecto de reforma jubilatoria planeada por el Gobierno de Frigerio, cuyo anticipo aparece en el documento Resumen Vectores.<\/strong><\/span><\/h3>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Son 9 puntos que no transcribo, pero son conocidos, aqu\u00ed me dedico a analizar uno por uno.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>1. Haber inicial<\/strong><\/span><\/h4>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u00a0Se sostiene el 82% liquidado sobre el bruto del haber. Se toma como base de c\u00e1lculo la historia laboral real del conjunto de haberes de los 30 a\u00f1os de aportes, tomando como metodolog\u00eda la de cargo por antig\u00fcedad a valores actuales.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">82% sobre el bruto remunerativo, no se tienen en cuenta los montos en negro.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Tomar 30 a\u00f1os de aporte genera que el haber jubilatorio pierda un gran porcentaje respecto a la f\u00f3rmula de c\u00e1lculo actual, que toma la situaci\u00f3n laboral de los \u00faltimos 10 a\u00f1os.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Analicemos dos situaciones que muestran con claridad la degradaci\u00f3n del salario que contiene este punto.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Jubilado\/a con una carrera que incluye 12 a\u00f1os de maestra (Sin NEP), 10 a\u00f1os de Directora de 1ra (NEP) y 8 a\u00f1os como Supervisora.<\/strong><\/span><\/h5>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Este docente cobra como activo justo antes de jubilarse <strong>$ 2.141.601<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con la ley 8732, haciendo un prorrateo de los \u00faltimos 10 a\u00f1os y sin el descuento extra del 3%: <strong>$ 1.993.695<\/strong>, que representa el <strong>93,1%<\/strong> del sueldo del activo, deber\u00eda ser m\u00e1s cercano al 100% pero la disminuci\u00f3n se debe a los montos en negro ilegales presentes en el salario.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con la ley 8732 y con el descuento extra del 3%: <strong>$ 1.931.065<\/strong>, que representa el <strong>90,2%<\/strong> del sueldo del activo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado en la misma situaci\u00f3n aplicando la f\u00f3rmula de la reforma, haciendo un prorrateo de 30 a\u00f1os: <strong>$1.576.016<\/strong>, que representa el <strong>79,1%<\/strong> del sueldo calculado con ley 8732 y el <strong>73,6%<\/strong> del sueldo del activo, es decir, al jubilarse pierde el <strong>26,4%<\/strong> del sueldo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con edad especial, varios a\u00f1os hasta llegar a la edad ordinaria, sufriendo un descuento del 19% en su haber: <strong>$ 1.193.634<\/strong>, que representa el <strong>59,8%<\/strong> del haber que hoy se calcula con la ley 8732 y el <strong>55,7%<\/strong> del sueldo en actividad, la reforma le quita el <strong>44,3%<\/strong> del sueldo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">La mayor\u00eda de los Supervisores y Supervisoras de Primaria tienen una carrera similar a la aqu\u00ed calculada, por lo tanto, para explicarlo en forma sencilla, la reforma le significar\u00e1 perder <strong>$ 947.967<\/strong> al momento de jubilarse respecto al sueldo de activo, o <strong>$ 737.431<\/strong> respecto al sueldo de jubilado calculado con la actual f\u00f3rmula de la ley 8732, que ya contiene la p\u00e9rdida por los montos en negro.<\/span><\/p>\r\n<p><br \/>Activo Actual $ 2.141.601 <br \/>Jubilado actual $ 1.993.695 93,1%<br \/>Jubilado pror 30 $ 1.576.016 73,6%<br \/>Jub con 19% $ 1.193.634 55,7%<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3654 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionprimaria-300x171.jpg\" alt=\"\" width=\"737\" height=\"420\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionprimaria-300x171.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionprimaria.jpg 577w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Jubilado\/a con una carrera que incluye 12 a\u00f1os iniciales con un promedio de 20 horas de nivel secundario, 10 a\u00f1os de Rector de 1ra con 12 horas y 8 a\u00f1os como Supervisora.<\/strong> (En los primeros a\u00f1os se consiguen pocas horas y podemos considerar que para muchos el promedio en los primeros 12 a\u00f1os es 20 horas)<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Este docente cobra como activo, justo antes de jubilarse <strong>$ 2.141.601<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con la ley 8732, haciendo un prorrateo de los \u00faltimos 10 a\u00f1os y sin el descuento extra del 3%: <strong>$ 2.022.264<\/strong>, que representa el <strong>94,4%<\/strong> del sueldo del activo, deber\u00eda ser m\u00e1s cercano al 100% pero la disminuci\u00f3n se debe a los montos en negro ilegales presentes en el salario.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con la ley 8732 y con el descuento extra del 3%: <strong>$ 1.958.737<\/strong>, que representa el <strong>91,5%<\/strong> del sueldo del activo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado en la misma situaci\u00f3n aplicando la f\u00f3rmula de la reforma, haciendo un prorrateo de 30 a\u00f1os: <strong>$1.578.148<\/strong>, que representa el <strong>78%<\/strong> del sueldo calculado con ley 8732 y el <strong>73,7%<\/strong> del sueldo del activo, es decir, al jubilarse pierde el <strong>26,3%<\/strong> del sueldo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Jubilado con edad especial, varios a\u00f1os hasta llegar a la edad ordinaria, sufriendo un descuento del 19% en su haber: <strong>$ 1.195.249<\/strong>, que representa el <strong>59,1%<\/strong> del haber que hoy se calcula con la ley 8732 y el <strong>55,8%<\/strong> del sueldo en actividad, la reforma le quita el <strong>44,2%<\/strong> del sueldo.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">La mayor\u00eda de los Supervisores y Supervisoras de Secundaria tienen una carrera similar a la aqu\u00ed calculada, por lo tanto, para explicarlo en forma sencilla, la reforma le significar\u00e1 perder <strong>$ 946.352<\/strong> al momento de jubilarse respecto al sueldo de activo, o <strong>$ 763.488<\/strong> respecto al sueldo de jubilado calculado con la actual f\u00f3rmula de la ley 8732, que ya contiene la p\u00e9rdida por los montos en negro.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Tengamos en cuenta adem\u00e1s, que la actual gesti\u00f3n de Frigerio ya empobreci\u00f3 el sueldo de activos y jubilados en un <strong>24,4%<\/strong>, si combinamos la p\u00e9rdida del poder adquisitivo del salario docente en general y la p\u00e9rdida por la pretendida reforma de la ley de jubilaciones, el caso analizado est\u00e1 percibiendo el <strong>42,1%<\/strong> de lo que cobraba ese mismo jubilado en noviembre de 2023, el mes anterior a la llegada de Frigerio a la Provincia de Entre R\u00edos, es decir, le habr\u00e1n quitado el <strong>57,9%<\/strong> de su salario, bastante m\u00e1s de la mitad.<\/span><\/p>\r\n<table width=\"349\">\r\n<tbody>\r\n<tr>\r\n<td width=\"148\">\r\n<p>Activo Actual<\/p>\r\n<\/td>\r\n<td width=\"129\">\r\n<p>\u00a0$ 2.141.601<\/p>\r\n<\/td>\r\n<td width=\"73\">\r\n<p>100%<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"148\">\r\n<p>Jubilado actual<\/p>\r\n<\/td>\r\n<td width=\"129\">\r\n<p>$ 2.022.264<\/p>\r\n<\/td>\r\n<td width=\"73\">\r\n<p>94,4%<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"148\">\r\n<p>Jubilado pror 30<\/p>\r\n<\/td>\r\n<td width=\"129\">\r\n<p>$ 1.578.148<\/p>\r\n<\/td>\r\n<td width=\"73\">\r\n<p>73,7%<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"148\">\r\n<p>Jub con 19%<\/p>\r\n<\/td>\r\n<td width=\"129\">\r\n<p>$ 1.195.249<\/p>\r\n<\/td>\r\n<td width=\"73\">\r\n<p>55,8%<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<p>&nbsp;<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3655 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionsecundaria-300x173.jpg\" alt=\"\" width=\"719\" height=\"415\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionsecundaria-300x173.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionsecundaria.jpg 723w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/p>\r\n<p>&nbsp;<\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Al igual que los ejemplos de carreras docentes, lo mismo sucede con otros sectores del Estado entrerriano, as\u00ed veremos que un Polic\u00eda que comenz\u00f3 su carrera como Agente y ascendi\u00f3 hasta Comisario, el haber jubilatorio en lugar de sostener el ascenso de su carrera, tomar\u00e1 todos sus a\u00f1os como Agente y degradar\u00e1 su salario a tiempos que quedaron muy detr\u00e1s en su historia laboral, ya no ser\u00e1 un Comisario Jubilado, tendr\u00e1 un haber que nada tiene que ver con su esfuerzo para construir su carrera.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Lo mismo sucede con un Estatal que ingres\u00f3 hace 30 a\u00f1os en Categor\u00eda 10 y se mantuvo ascendiendo por sus m\u00e9ritos hasta la Categor\u00eda 1, al jubilarse no se tendr\u00e1 en cuenta su situaci\u00f3n reciente y se incluir\u00e1n los peores a\u00f1os de su carrera, degradando su Categor\u00eda al Jubilarse.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Aqu\u00ed hay que tener en cuenta que los empleados estatales y los polic\u00edas, hoy tienen un enorme porcentaje de montos en negro en su salario, que aunque crean que su sueldo tiene un valor determinado, para el c\u00e1lculo del haber jubilatorio es alrededor de un 30% menos, quitando los montos en negro queda un sueldo de ingiencia, pues bien, ese sueldo de indigencia ser\u00e1 utilizado 30 a\u00f1os despu\u00e9s para degradar el haber jubilatorio y llevarlo seguramente a la mitad de lo que perciban en ese momento. El gobernador que hace 9 meses que no aplica aumentos en blanco a estatales y polic\u00edas y lo mismo sucede con docentes hace 3 meses, que de esta forma est\u00e1 deteriorando el haber jubilatorio presente y futuro, vuelve a golpear al mismo sector con un proyecto para triplicar el da\u00f1o producido. \u00bfA alguien le pueden quedar dudas que si nos sometemos a estos planes tendremos una vejez sumida en la mendicidad?<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Este principio de No Degradaci\u00f3n de la carrera est\u00e1 establecido en los sistemas jubilatorios, es por eso que se prorratean los \u00faltimos 5 o 10 a\u00f1os para el c\u00e1lculo del haber, la ley 8732 establece 10 a\u00f1os, el proyecto de reforma previsional elimina este principio sin otro fundamento que no sea el de recortar el salario de los trabajadores al acceder a su jubilaci\u00f3n.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Se sigue tomando en concepto de antig\u00fcedad la \u00faltima de la carrera.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>2. Reg\u00edmenes especiales<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">En este punto la reforma es profundamente regresiva, en principio se dice que se respetar\u00e1n todas las edades actuales, pero posteriormente indica que, si bien se podr\u00e1 acceder al beneficio jubilatorio a las edades especiales, se continuar\u00e1 descontando el aporte jubilatorio, del 19%, hasta la edad ordinaria, por lo que se reducir\u00e1 respecto a los haberes actuales en un 16% y respecto a los haberes anteriores a junio de 2024 en un 19%, porque desde ese momento se descuenta el 3%.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Si analizamos esta situaci\u00f3n jubilatoria podemos entender que una mujer acceder\u00e1 a un retito anticipado a los 52 a\u00f1os con una quita del 19% del salario hasta los 57 a\u00f1os y un var\u00f3n estar\u00e1 en esta situaci\u00f3n desde los 54 a los 62 a\u00f1os.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Cada docente deber\u00e1 elegir entre jubilarse a la edad especial resignando el 19% del salario o continuar trabajando hasta la edad ordinaria para no perder salario.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Los aportes que se realicen en el lapso entre edad especial y edad ordinaria se considerar\u00e1n aporte solidario, no se considerar\u00e1n aportes que impacten en el c\u00e1lculo jubilatorio. Si entendemos su significado, ser\u00e1n jubilados que sostengan solidariamente los recursos de la Caja sacrificando salario que hoy es parte de su sustento.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>3. Movilidad<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Se rompe totalmente el concepto de movilidad, se lo desengancha de la situaci\u00f3n laboral de los activos, cambi\u00e1ndose por un \u00edndice de movilidad nacional, que ya conocemos y que genera salarios jubilatorios en valores que nada tienen que ver con los salarios de los trabajadores activos. Actualmente los jubilados docentes son \u201cdocentes jubilados\u201d, aunque parezca un juego de palabras, con la reforma dejar\u00e1n de ser docentes en cuanto a su salario, de esta forma encontraremos situaciones tales como, un cargo jubilado que ya lleva 5 a\u00f1os en esta situaci\u00f3n, ser\u00e1 muy diferente a ese mismo cargo jubilado en el momento actual, porque uno se calcular\u00e1 con el sueldo de los activos y el otro depender\u00e1 de la movilidad nacional.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Si observamos lo sucedido con la movilidad nacional entenderemos que la reforma nos va a introducir en una terrible incertidumbre, tenemos que recordar que en estos a\u00f1os hemos tenido cambios en las f\u00f3rmulas de movilidad, meses sin que el \u00edndice evolucione, todo esto ha hecho que los salarios de jubilados hayan perdido enormes porcentajes de poder adquisitivo y ya no tengan formas de recuperarlo, es decir, si esas incertidumbres hacen que el salario se caiga, ya nunca se recupera. Insisto, para entender esto, s\u00f3lo hay que mirar lo que ha sucedido en los \u00faltimos a\u00f1os.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Respecto a quienes ya est\u00e1n jubilados, si bien se habla de respetar los derechos adquiridos, el Presidente de la Caja de Jubilaciones ha declarado en la prensa que la forma de aplicar la movilidad va a cambiar para todos, incluso para quienes ya est\u00e1n jubilados. Esto significa que se desengancha el haber del activo y se mueve por el \u00edndice de movilidad nacional, quienes ya est\u00e9n jubilados no se salvar\u00edan de poner su ingreso en manos de la inceretidumbre y las decisiones pol\u00edticas.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">En este aspecto, en el de movilidad, es donde entran en riesgo todos los jubilados, de todos los sectores, porque ser\u00e1 aplicable a todas las jubilaciones. \u00bfy esto es grave? Para respondernos esta pregunta s\u00f3lo tenemos que observar lo que ha sucedido a nivel nacional, este \u00edndice se ha movido de acuerdo a decisiones pol\u00edticas antojadizas y ha hecho empobrecer al extremo a los jubilados.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Quienes quieran conocer su futuro como jubilados, sean del sector que sean, Polic\u00edas, Salud, Estatales o Docentes, el efecto del \u00edndice de movilidad del ANSES, s\u00f3lo tienen que mirar la evoluci\u00f3n de las jubilaciones nacionales, nos quieren llevar a todos a la m\u00ednima, justificable desde la mirada de este sector que gobierna, LOS JUBILADOS SON UNA CARGA PARA LA SOCIEAD, que es la misma mirada de la Argentina del Siglo XIX y principios del XX. Es el mismo sector de gobierno que apalea a nuestros viejos todos los jueves y les quitan remedios para que se mueran m\u00e1s r\u00e1pido.<\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3657 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacioncaidas-300x191.jpg\" alt=\"\" width=\"625\" height=\"398\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacioncaidas-300x191.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacioncaidas.jpg 635w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>4. Todos los beneficios del sistema<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Con este punto tenemos que volver al punto 2, all\u00ed dec\u00edamos que se perder\u00e1 un 19% del sueldo porque se deber\u00e1 seguir aportando hasta la edad ordinaria, 5 a\u00f1os las mujeres y 8 a\u00f1os los varones, pero al analizarlo con este punto, esa diferencia de a\u00f1os se ir\u00e1 ampliando en la medida de que la edad jubilatoria se vaya acrecentando. Espec\u00edficamente, a partir del 5to a\u00f1o, la edad se corre un a\u00f1o cada dos a\u00f1os, en los 8 a\u00f1os que sufrir\u00e1 el descuento un var\u00f3n, le aumentar\u00e1 la diferencia en 2 a\u00f1os. Pasando en limpio, de acuerdo al punto 2 dec\u00edamos que un var\u00f3n sufrir\u00e1 la quita del 19% del salario durante 8 a\u00f1os, ahora debemos decir 10 a\u00f1os y una mujer, puede pasar de 5 a\u00f1os a 7,5 a\u00f1os, 10 a\u00f1os o 7,5 a\u00f1os cobrando el 81% del haber que deber\u00eda cobrar.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">5. <strong>FUENTES DE FINANCIACI\u00d3N DEL SISTEMA.- <\/strong>Art12<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Si bien este punto ya estaba en la ley 8732, muy pocas veces se aplic\u00f3, reci\u00e9n se aplic\u00f3 el aumento del 3% con la llegada de este gobierno y si no me equivoco en tiempos de Moine, es decir, es un recurso que s\u00f3lo hay utilizado los gobiernos anti populares que vienen a recortar derechos de los trabajadores, lo mencionan expresamente porque tienen claro que recurrir\u00e1n a su utilizaci\u00f3n, \u201ccuando circunstancias extraordinarias debidamente acreditadas evidencien desequilibrios financieros\u201d, que es lo que est\u00e1n anunciando en este momento, pondr\u00e1n en cero el d\u00e9ficit y lo har\u00e1n recortando nuestro salario a niveles extremos, luego aclaran \u201cTales aportes deber\u00e1n aplicarse con criterios de razonabilidad, proporcionalidad y progresividad\u201d, dado que conocemos los criterios de este gobierno, ser\u00e1 la razonabilidad de atentar contra la vida de los trabajadores jubilados, tal cual lo est\u00e1n haciendo ahora.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>6. PENSIONES POR FALLECIMIENTO Y POR INVALIDEZ y EDAD AVANZADA.-<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Se modificar\u00e1n los criterios y f\u00f3rmulas actuales, cambi\u00e1ndolos por los criterios y f\u00f3rmulas nacionales. Deberemos estudiar estos criterios para comprender el cambio.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">8. Municipios<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">9. Edades<\/span><\/p>\r\n<figure class=\"wp-block-table\" style=\"text-align: justify;\">\r\n<table class=\"has-fixed-layout\" style=\"height: 484px;\" width=\"795\">\r\n<tbody>\r\n<tr>\r\n<td style=\"height: 10px; width: 200px;\"><span style=\"font-size: 12pt;\">A\u00d1OS PARA JUBILARSE<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">5<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">7<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">9<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">11<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">13<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">15<\/span><\/td>\r\n<td style=\"height: 10px;\"><span style=\"font-size: 12pt;\">17<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"width: 300px; height: 50px;\"><span style=\"font-size: 12pt;\">HOMBRE<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">62<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">62,5<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">63<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">63,5<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">64<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">64,5<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">65<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"width: 300px; height: 50px;\"><span style=\"font-size: 12pt;\">MUJER<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">57<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">57,5<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">58<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">58,5<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">59<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">59,5<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">60<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"width: 300px; height: 50px;\"><span style=\"font-size: 12pt;\">A\u00d1OS APORTE<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">30<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">31<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">32<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">33<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">34<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">35<\/span><\/td>\r\n<td style=\"width: 100px; height: 15px;\"><span style=\"font-size: 12pt;\">35<\/span><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/figure>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Esta es la tabla de incremento de edades y aqu\u00ed hay muchas cuestiones para evaluar.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">En principio no determina si las edades de jubilaci\u00f3n especial quedar\u00e1n como hasta hoy o tendr\u00e1n cambios similares, pero de todas formas perjudica a estos sectores porque aumenta los a\u00f1os de sueldos recortados en un 19%, as\u00ed, un var\u00f3n que se jubile a los 54 a\u00f1os dentro de 17 a\u00f1os, sufrir\u00e1 el recorte del 19% de su sueldo durante 11 a\u00f1os y una mujer durante 8 a\u00f1os.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Este recorte del 19% del sueldo es una clara invitaci\u00f3n a no acceder al beneficio en la edad especial, invitaci\u00f3n que se hace obligaci\u00f3n desesperante ante sueldos actuales de jubilados que ya est\u00e1n muy por debajo de la l\u00ednea de la pobreza.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Para poner estas afirmaciones en n\u00fameros, actualmente una maestra jubilada percibe un haber de $ 1.023.743, con una l\u00ednea de la pobreza de $ 1.397.672, esto representa el 73,2% de la l\u00ednea de la pobreza, pero quienes se jubilan y son menores a la edad ordinaria, sufren un descuento del 3% y su salario queda en $ 991.718, que representa el 71% de la l\u00ednea de la pobreza, con la reforma, sufrir\u00e1n un descuento del 19%, el haber de bolsillo quedar\u00eda en $ 820.916, es decir el 58% de la l\u00ednea de la pobreza y muy cerca de la l\u00ednea de indigencia\u00a0 cuyo valor es $ 644.088.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Resumimos en el siguiente cuadro las situaciones de un\/a jubilado\/a en cargo de maestra.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<figure class=\"wp-block-table\" style=\"text-align: justify;\">\r\n<table class=\"has-fixed-layout\">\r\n<tbody>\r\n<tr>\r\n<td><span style=\"font-size: 12pt;\">L\u00ednea de la Pobreza<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">1.397.672,00<\/span><\/td>\r\n<td>\u00a0<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><span style=\"font-size: 12pt;\">Jubilado edad ordinaria<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">1.023.743,00<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">73,2%<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><span style=\"font-size: 12pt;\">Jubilado actual edad especial<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">991.718,00<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">71,0%<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><span style=\"font-size: 12pt;\">Jubilado con reforma en edad especial<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">820.916,00<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">58,7%<\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><span style=\"font-size: 12pt;\">L\u00ednea de la Indigencia<\/span><\/td>\r\n<td><span style=\"font-size: 12pt;\">$ 644.088<\/span><\/td>\r\n<td>\u00a0<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/figure>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3656 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionmaestra-300x152.jpg\" alt=\"\" width=\"711\" height=\"360\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionmaestra-300x152.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionmaestra-768x388.jpg 768w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/graficobajajubilacionmaestra.jpg 801w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Aclaraci\u00f3n necesaria<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El an\u00e1lisis aqu\u00ed realizado se hace sobre el documento Resumen Vectores presentado por el gobierno, que no es el verdadero proyecto.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Quiero expresar que me cost\u00f3 ponerme a analizarlo, porque estoy convencido de que es un documento para distraernos y que el verdadero proyecto de reforma ser\u00e1 a\u00fan peor y no lo conoceremos hasta despu\u00e9s de votado, porque al tener los votos ya asegurados, los propios y los comprados a traidores de la oposici\u00f3n, al igual que sucedi\u00f3 con OSER, presentar\u00e1n un proyecto cerrado que intentar\u00e1n votar sin siquiera saber lo que votan, exactamente la misma metodolog\u00eda que se utiliz\u00f3 para aprobar la reforma laboral.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Es nuestra vida la que est\u00e1 en juego<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Y tenemos que dar la vida para defender nuestro derecho jubilatorio<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Hago un llamamiento a activos y jubilados a frenar en las calles este plan macabro para destruirnos la vida de jubilados, que se suma al que ya implementaron para quitarnos el 24,4% del sueldo que en Mayo llegar\u00e1 al 34,2% por sueldos congelados e inflaci\u00f3n sostenida.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">A quienes son solidarios les pido que sumen sus fuerzas a defender el ingreso de los jubilados, que es defender la subsistencia, por eso hablo de defender la vida.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">A quienes son ego\u00edstas y s\u00f3lo piensan en si mismos, les digo que sumen su fuerza a la lucha para defender la vida de ese viejito o viejita que ser\u00e1 dentro de unos a\u00f1os, porque todos seremos jubilados, defender a los jubilados no es defender a otros, es defendernos a nosotros mismos en la etapa en que nuestras fuerzas comiencen a ceder.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">A los m\u00e1s j\u00f3venes les digo, son los m\u00e1s afectados por esta reforma, porque por lo explicado m\u00e1s arriba, el paso de los a\u00f1os ir\u00e1 empeorando el sistema jubilatorio, tal como est\u00e1 estipulado en este proyecto.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">A vos te digo, joven todo poderoso con un cuerpo sin padecimientos, ponete un poquito a pensar, no vas a ser joven toda la vida, esa vejez que hoy ves tan lejos, esos viejos a los que hoy ves como alejados de tu vida, sos vos en el futuro, si no te das cuenta de eso ahora y sal\u00eds a defender los derechos, llegar\u00e1s a viejo sumergido en la indigencia y esos viejos que en su juventud lucharon por los derechos que hoy disfrut\u00e1s, ya no estar\u00e1n para defenderte, habr\u00e1n muerto en la m\u00e1s extrema pobreza.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>JUBILACIONES COMO MIRADA IDEOL\u00d3GICA<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El sistema jubilatorio no tiene un &#8220;deber ser&#8221; m\u00e1gico o natural, es una expresi\u00f3n de la mirada humanitaria de cada momento hist\u00f3rico, el primer sistema jubilatorio en la Argentina data del 1904, hasta finales del siglo XIX las personas mayores deb\u00edan trabajar hasta que le dieran sus fuerzas, luego depend\u00edan de la ayuda familiar y generalmente terminaban en la mendicidad hasta la muerte por imposibilidad de subsistencia. En 1904 se crea la primer Caja de Jubilaciones de empleados del Estado y Ferrocarriles, en 1954 se crea el sistema de reparto, pero en 1994 se rompe el sistema de reparto y se crean las AFJP, que representaron un retroceso hist\u00f3rico del derecho a la jubilaci\u00f3n establecido 40 a\u00f1os antes. En 2008 se reestatiz\u00f3 el sistema, ante el colapso de las AFJP que s\u00f3lo representaban un negocio financiero y condenaban a los jubilados a la extrema pobreza. Tambi\u00e9n desde comienzos de los a\u00f1os 2000 aparecieron las moratorias previsionales, bajo la convicci\u00f3n de que la condici\u00f3n de trabajo en negro no era una responsabilidad de los trabajadores precarizados sino de sus empleadores y el Estado se convert\u00eda en garante de derechos, esas moratorias se comenzaron a eliminar desde diciembre de 2023, negando el derecho jubilatorio a quienes fueron v\u00edctimas de la precarizaci\u00f3n en su vida laboral.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">La ley 8732 en Entre R\u00edos refleja una mirada de derechos, fue el producto de una historia de lucha, no es una ley natural, surge de un estado de disputa y conquista de derechos, siempre dijimos que era nuestro deber como trabajadores defenderla, porque vendr\u00edan por ella en otras relaciones de poder, lleg\u00f3 ese momento, hoy nos gobierna un sector pol\u00edtico que reivindica las relaciones laborales del siglo XIX y comienzos del XX, en cuanto a relaciones laborales retrocedieron la conquista de las 8 horas como m\u00e1ximo, quitaron la indemnizaci\u00f3n como resguardo a los despidos indiscriminados de las patronales, volvieron a dar poder absoluto a las patronales en las relaciones laborales y, como era de esperar, tambi\u00e9n pretenden retrotraer el derecho a una jubilaci\u00f3n digna. No es un capricho o decisi\u00f3n equivocada de Frigerio y el sector al que representa, es la esencia que sustenta a ese sector social olig\u00e1rquico, que es minoritario, pero que hoy tiene un poder que le permite imponer su desprecio por la clase trabajadora, que se traduce empobrecer a los trabajadores al momento de jubilarse y dejar de producir riquezas que ellos acumulan como patronales.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Claro que yo respeto las decisiones personales al momento de votar en nuestra democracia, pero sinceramente estoy convencido que muchos se equivocaron, porque defender el derecho a la jubilaci\u00f3n digna y haber entregado el poder al sector que considera que los viejos que no generan riquezas deben empobrecerse hasta caer en la mendicidad, como en el siglo XIX, es un voto equivocado, es un voto en contra de las propias convicciones. Pero el pueblo no tiene la culpa de equivocarse con el voto, el poder tiene sus recursos para enga\u00f1arnos y la equivocaci\u00f3n es siempre posible, lo que nos corresponde ahora es corregir ese error, dejar de apoyar a los que gobiernan en contra de la clase trabajadora y salir a reclamar ante el enga\u00f1o electoral, salir a expresarle que el voto no implicaba bancar que nos destruyan la escuela p\u00fablica, la salud p\u00fablica, el salario que es sustento de nuestra vida y la jubilaci\u00f3n que garantiza una vejez con dignidad humana. No importa a quien votaron, lo que estoy seguro es que la mayor\u00eda del pueblo entrerriano no vot\u00f3 para nos hicieran esto y la democracia nos permite reclamar y peticionar, el voto no significa que nos condena por 4 a\u00f1os a que nos pisoteen como se les antoje. Si ya nos dimos cuenta del enga\u00f1o, el respeto por nuestra dignidad nos obliga a salir a la calle a gritar que no aceptamos la traici\u00f3n de un gobernador como Frigerio que gobierna contra nosotros y no para nosotros.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Ya no hay tiempo para lamentos en tu casa, tu reclamo se debe expresar en las calles o no existe, el lamento encerrado en tu casa es la convalidaci\u00f3n de la reforma que destruye nuestra vida como jubilados, que es la continuidad de la destrucci\u00f3n que sufrimos como trabajadores con gigantescos recortes del poder adquisitivo de nuestro salario.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>LA REFORMA PREVISIONAL DE FRIGERIO SE PRETENDE IMPONER PARA QUE LE CIERREN LOS N\u00daMEROS AL SAQUEO DE MILEI<\/strong><\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">La Caja de Jubilaciones es una de las tantas Cajas provinciales que son administradas por cada provincia, en acuerdo con el sistema jubilatorio nacional.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El sistema jubilatorio nacional se sostiene en parte con aportes de los trabajadores y en parte con aportes del tesoro nacional, para lo cual existen leyes que recaudan esos fondos para garantizar la seguridad, que implica varias cuestiones y entre ellas el sistema jubilatorio. El sistema jubilatorio entrerriano tiene un mayor aporte de parte de los trabajadores, el porcentaje en general es del 11% y en Entre R\u00edos es del 16% y, desde la llegada de Frigerio, se increment\u00f3 a 19% incluyendo adem\u00e1s un aporte del 3% para jubilados especiales.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Desde la sanci\u00f3n de la ley 8732, en 1993, el Estado Nacional se comprometi\u00f3 a girar los fondos a la provincia para sostener el r\u00e9gimen jubilatorio, lo que hizo que siempre funcione en equilibrio y sin recortes que empobrezcan a los trabajadores jubilados, lo que muchos intentan mostrar como \u201cD\u00e9ficit\u201d, es en realidad la componente del tesoro nacional y tambi\u00e9n provincial, que se debe sumar a los sistemas jubilatorios para garantizar el derecho establecido por la Constituci\u00f3n Nacional en su art\u00edculo 14 bis.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">En los a\u00f1os anteriores se han hecho ajustes y correcciones en el sistema jubilatorio, as\u00ed fue que se quit\u00f3 el llamado 3 por 1 en jubilaciones docentes, se ajust\u00f3 a la ley en cuanto a la caja otorgante y algunas cuestiones menores y, ya en la gesti\u00f3n Frigerio, se aument\u00f3 el aporte jubilatorio al 19% y se carg\u00f3 a los mismos jubilados con un 3% de aporte.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Hoy nos hablan de una gran crisis que no se puede sostener, pero este problema se genera por la quita de fondos nacionales que deben ser coparticipados a las provincias, que forma parte de un problema mucho mayor que s\u00f3lo las jubilaciones, porque nuestra provincia lo sufre en falta de recursos para salud, educaci\u00f3n e infraestructura vial que est\u00e1 haciendo colapsar nuestras rutas nacionales y provinciales.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Concretamente, el problema de la Caja de Jubilaciones es una consecuencia del recorte nacional a los fondos provinciales, es un problema del federalismo de los recursos, de que el Estado nacional se queda con los fondos que deber\u00edan volver a las provincias y los destina a la especulaci\u00f3n financiera, a sostener un d\u00f3lar ficticio al que lo sostiene con los fondos que le retiene a las provincias y por otro lado vemos que las provincias se tienen que hacer cargo de sostener todas las necesidades de la sociedad y se no tiene los recursos.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El gobernador Frigerio es absolutamente corresponsable de esta apropiaci\u00f3n de recursos de parte del Estado nacional, porque ha acompa\u00f1ado en la legislatura todas las leyes de presupuesto que permiten al gobierno nacional el vaciamiento de recursos a las provincias, esto necesariamente le genera situaciones insostenibles.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El proyecto de reforma previsional de Frigerio intenta hacer pagar a los trabajadores entrerrianos, estatales, polic\u00edas, docentes, judiciales y personal de salud, los costos de haber entregado nuestros recursos a los planes especulativos de Milei, que adem\u00e1s destruyen la econom\u00eda provincial y genera empobrecimiento de la producci\u00f3n industrial.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Es as\u00ed que pretende aumentar en 5 a\u00f1os los a\u00f1os de aporte, reducir el haber jubilatorio modificando la f\u00f3rmula de c\u00e1lculo, los trabajadores del Estado tienen que saber que deber\u00e1n trabajar 5 a\u00f1os m\u00e1s y cobrar\u00e1n mucho menos al momento de jubilarse, pero esto no es lo peor, porque luego su haber jubilatorio ser\u00e1 desenganchado del haber de los activos y navegar\u00e1 por un \u00edndice de movilidad totalmente manipulable por los gobiernos, que llevar\u00e1 su haber a perder en forma permanente, que con el paso de los a\u00f1os evolucionar\u00e1 al mismo valor que hoy vemos en las jubilaciones nacionales.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Frigerio ha tenido la disyuntiva de acompa\u00f1ar los planes de saque de Milei a la clase trabajadora o respetar el derecho jubilatorio de los trabajadores que sostienen la provincia, que la sostienen desde mucho tiempo antes de que \u00e9l desembarque con su tropa en nuestras tierras y que la seguir\u00e1n sosteniendo cuando emprenda vuelo y se retire de la provincia a seguir su carrera pol\u00edtica por otras tierras, decidi\u00f3 que su permanencia temporal en Entre R\u00edos sea para garantizar el saqueo planeado por Milei y su banda, fue as\u00ed que tambi\u00e9n aport\u00f3 los votos para la ley bases, para la reforma laboral y tantas tragedias m\u00e1s que nos est\u00e1n imponiendo en estos tiempos.<\/span><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Entre R\u00edos ha sido una provincia de lucha en toda su historia, desde las batallas por el federalismo ante los gobiernos unitarios, pero tambi\u00e9n en nuestra historia reciente, hoy cada uno de nosotros tiene que decidir si vamos a permitir que un porte\u00f1o que vino a saquearnos para la corona unitaria cumpla con sus planes o levantaremos nuestras banderas y saldremos a las calles a resistir al impostor que nada tiene que ver con la vida de los entrerrianos.<\/span><\/p>\r\n<h4>El \u00cdndice de movilidad nos deja en el fondo del pozo respecto a futuras conquistas de los trabajadores o cambio de pol\u00edticas salariales<\/h4>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">El salario de trabajadores activos y jubilados se encuentra en el peor momento de la historia, en niveles similares a los del 2.001. Si recordamos el proceso hist\u00f3rico de 2.001 a 2.015, las luchas sindicales y los cambios de gobierno hicieron que el valor adquisitivo del salario duplicara y m\u00e1s al de 2.001, es as\u00ed que la recuperaci\u00f3n fue de salarios de trabajadores activos y por el enganche que establece la Ley 8732, recorri\u00f3 el mismo camino de recuperaci\u00f3n y a\u00fan m\u00e1s, porque en aquel proceso logramos quitar los c\u00f3digos en negro, por lo que la recuperaci\u00f3n salaria de jubilados fue a\u00fan mayor que la de activos. Hoy todos creemos que construiremos una recuperaci\u00f3n similar, porque no puede quedar como est\u00e1 hoy y no puede seguir bajando, con luchas sindicales, con paritarias y con otros gobiernos, el salario necesariamente tiene que dar un salto en cuanto al poder adquisitivo. Si se aplica el \u00edndice de movilidad que pretende el gobierno con la reforma previsional, este salario actual, que se encuentra en el pozo m\u00e1s profundo de nuestra historia, quedar\u00e1 fijado para siempre en ese nivel y el \u00edndice no le permitir\u00e1 recuperar poder adquitivo, por el contrario, las variaciones de este \u00edndice siempre son a la baja, por lo que la pobreza que sufrimos hoy trabajadores y jubilados, quedar\u00e1 instalada para siempre en el haber jubilatorio, con la \u00fanica posibilidad de bajar, pero no subir por las consquistas salariales de las luchas de los trabajadores. Definitvamente, el plan es empobrecer a los jubilados, aunque nos digan que quieren cuidar las jubilaciones o prometan con enga\u00f1o mantener el 82% actual, sostener el 82% m\u00f3vil implica mantener la relaci\u00f3n que siempre tuvo con el salario de los activos.<\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3648 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/jubilacioneshundidasporindice-300x300.jpg\" alt=\"\" width=\"557\" height=\"557\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/jubilacioneshundidasporindice-300x300.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/jubilacioneshundidasporindice-150x150.jpg 150w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/jubilacioneshundidasporindice-768x768.jpg 768w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/jubilacioneshundidasporindice.jpg 800w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/p>\r\n<p><span style=\"font-size: 12pt;\">\r\n\r\n<\/span><\/p>\r\n<h4>SOBRE EL 82% EN JUBILACIONES DE ENTRE R\u00cdOS<\/h4>\r\n<p>Hemos escuchado en estos d\u00edas, tanto al Gobernador como al Presidente de la Caja de Jubilaciones de Entre R\u00edos, expresar por los medios de prensa que los jubilados entrerrianos percibimos m\u00e1s que el 82%, mencionando cifras como 100% y hasta 110%, es necesario iluminar con verdad estas expresiones, que no son errores, son mentiras, porque quienes lo salen a expresar tienen conocimiento del tema del que hablan.<\/p>\r\n<p>La ley 8732 expresa que el sueldo nominal del activo se toma como base para el c\u00e1lculo del haber jubilatorio, aplic\u00e1ndosele al mismo un 82% de dicho valor y es exactamente esto lo que se hace al aplicar las f\u00f3rmulas de haberes jubilatorios.<\/p>\r\n<p>El haber jubilatorio tiene una quita al aplicar el 82% del 18% de su valor, lo que tenemos que saber es lo que sucede con estos sueldos nominales para convertirse en sueldos l\u00edquidos.<\/p>\r\n<p>Al sueldo nominal del activo se le aplica un descuento del 22%, compuesto de 19% de aporte jubilatorio y 3% de aporte a obras sociales.<\/p>\r\n<p>El Nominal del jubilado sufre un descuento que puede ser del 3,5% o del 6,5% aproximadamente, porque podr\u00eda contener un 3% de aporte jubilatorio hasta la edad ordinaria.<\/p>\r\n<p>Esta diferencia de descuentos es la que genera que los sueldos l\u00edquidos queden en valores similares, que ese recorte del 18% se compense con el hecho de que el jubilado deja de aportar 16% a la Caja de jubilaciones.<\/p>\r\n<p>Este hecho no es ninguna novedad en nuestra provincia ni en ninguna otra, cualquiera que analice brevemente podr\u00e1 entender que no se deben comparar sueldos l\u00edquidos para ver el efecto del 82%, sino sueldos nominales, que es as\u00ed como se hace. El Presidente de la Caja de Jubilaciones es experto en normas previsionales, no tengo dudas de que entiende claramente esta explicaci\u00f3n, no lo estoy explicando para \u00e9l, entonces, si lo sabe y dice otra cosa, tengo que entender que est\u00e1 mintiendo descaradamente.<\/p>\r\n<p>Pero en realidad, si vamos a ser estrictos con el 82%, debemos considerar todo el sueldo de los activos, entre los que se encuentran montos en negro recientemente incluidos, que no son tenidos en cuenta para el c\u00e1lculo del haber jubilatorio y esto es una ilegalidad que se traduce en que en realidad recibimos aproximadamente un 10% menos que el 82% del Sueldo Nominal, si vamos a discutir sobre el 82%, lo primero que debieran hacer es legalizar las sumas en negro para que sean parte del c\u00e1lculo del haber de sueldos de jubilados.<\/p>\r\n<p>Acompa\u00f1o con un gr\u00e1fico en el cual se pueden visualizar los sueldos nominales, los descuentos, los sueldos l\u00edquidos y los montos en negro ilegales, all\u00ed se visualiza el efecto del 82% y la diferencia de descuentos entre activos y jubilados.<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3659 aligncenter\" src=\"http:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/aplicacion82-300x300.jpg\" alt=\"\" width=\"492\" height=\"492\" srcset=\"https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/aplicacion82-300x300.jpg 300w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/aplicacion82-150x150.jpg 150w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/aplicacion82-768x768.jpg 768w, https:\/\/victorhutt.com.ar\/wp-content\/uploads\/2026\/03\/aplicacion82.jpg 800w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">V\u00edctor Hutt<\/span><\/p>\r\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_3614\" class=\"pvc_stats all  \" data-element-id=\"3614\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/victorhutt.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>An\u00e1lisis del proyecto de reforma jubilatoria planeada por el Gobierno de Frigerio, cuyo anticipo aparece en el documento Resumen Vectores. Son 9 puntos que no transcribo, pero son conocidos, aqu\u00ed me dedico a analizar uno por uno. 1. Haber inicial \u00a0Se sostiene el 82% liquidado sobre el bruto del haber. Se toma como base de c\u00e1lculo la historia laboral real del conjunto de haberes de los 30 a\u00f1os de aportes, tomando como metodolog\u00eda la de cargo por antig\u00fcedad a valores actuales. 82% sobre el bruto remunerativo, no se tienen en cuenta los montos en negro. Tomar 30 a\u00f1os de aporte<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_3614\" class=\"pvc_stats all  \" data-element-id=\"3614\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/victorhutt.com.ar\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[33],"tags":[],"class_list":["post-3614","post","type-post","status-publish","format-standard","hentry","category-mistextos"],"a3_pvc":{"activated":true,"total_views":74,"today_views":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":10,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3614\/revisions"}],"predecessor-version":[{"id":3660,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3614\/revisions\/3660"}],"wp:attachment":[{"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/victorhutt.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}